{"id":4210,"date":"2021-03-30T08:42:36","date_gmt":"2021-03-30T08:42:36","guid":{"rendered":"https:\/\/www.fundaciocatalunyacultura.cat\/premi-empresa-cultura\/"},"modified":"2026-07-07T09:10:27","modified_gmt":"2026-07-07T09:10:27","slug":"premi-empresa-cultura","status":"publish","type":"page","link":"https:\/\/fundaciocatalunyacultura.cat\/es\/premi-empresa-cultura\/","title":{"rendered":"Premio EMPRESA CULTURA"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-premi-empresa-cultura.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-4210","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Premio EMPRESA CULTURA | Fundaci\u00f3 Catalunya Cultura<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fundaciocatalunyacultura.cat\/es\/premi-empresa-cultura\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Premio EMPRESA CULTURA | Fundaci\u00f3 Catalunya Cultura\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fundaciocatalunyacultura.cat\/es\/premi-empresa-cultura\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3 Catalunya Cultura\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fundaciocatalunyacultura\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-07T09:10:27+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@fcatcultura\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/fundaciocatalunyacultura.cat\/es\/premi-empresa-cultura\/\",\"url\":\"https:\/\/fundaciocatalunyacultura.cat\/es\/premi-empresa-cultura\/\",\"name\":\"Premio EMPRESA CULTURA | Fundaci\u00f3 Catalunya Cultura\",\"isPartOf\":{\"@id\":\"https:\/\/fundaciocatalunyacultura.cat\/#website\"},\"datePublished\":\"2021-03-30T08:42:36+00:00\",\"dateModified\":\"2026-07-07T09:10:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/fundaciocatalunyacultura.cat\/es\/premi-empresa-cultura\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/fundaciocatalunyacultura.cat\/es\/premi-empresa-cultura\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/fundaciocatalunyacultura.cat\/es\/premi-empresa-cultura\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\/\/www.fundaciocatalunyacultura.cat\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Premio EMPRESA CULTURA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/fundaciocatalunyacultura.cat\/#website\",\"url\":\"https:\/\/fundaciocatalunyacultura.cat\/\",\"name\":\"Fundaci\u00f3 Catalunya Cultura\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/fundaciocatalunyacultura.cat\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/fundaciocatalunyacultura.cat\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/fundaciocatalunyacultura.cat\/#organization\",\"name\":\"Fundaci\u00f3 Catalunya Cultura\",\"url\":\"https:\/\/fundaciocatalunyacultura.cat\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/fundaciocatalunyacultura.cat\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/fundacio-catalunya-cultura\/uploads\/2021\/03\/fcc_logo_blanc-scaled.jpeg\",\"contentUrl\":\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/fundacio-catalunya-cultura\/uploads\/2021\/03\/fcc_logo_blanc-scaled.jpeg\",\"width\":2560,\"height\":1785,\"caption\":\"Fundaci\u00f3 Catalunya Cultura\"},\"image\":{\"@id\":\"https:\/\/fundaciocatalunyacultura.cat\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/fundaciocatalunyacultura\/\",\"https:\/\/x.com\/fcatcultura\",\"https:\/\/www.linkedin.com\/company\/fundaci\u00f3-catalunya-cultura\/\",\"https:\/\/ca.wikipedia.org\/wiki\/Fundaci\u00f3_Catalunya_Cultura\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Premio EMPRESA CULTURA | Fundaci\u00f3 Catalunya Cultura","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fundaciocatalunyacultura.cat\/es\/premi-empresa-cultura\/","og_locale":"es_ES","og_type":"article","og_title":"Premio EMPRESA CULTURA | Fundaci\u00f3 Catalunya Cultura","og_url":"https:\/\/fundaciocatalunyacultura.cat\/es\/premi-empresa-cultura\/","og_site_name":"Fundaci\u00f3 Catalunya Cultura","article_publisher":"https:\/\/www.facebook.com\/fundaciocatalunyacultura\/","article_modified_time":"2026-07-07T09:10:27+00:00","twitter_card":"summary_large_image","twitter_site":"@fcatcultura","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fundaciocatalunyacultura.cat\/es\/premi-empresa-cultura\/","url":"https:\/\/fundaciocatalunyacultura.cat\/es\/premi-empresa-cultura\/","name":"Premio EMPRESA CULTURA | Fundaci\u00f3 Catalunya Cultura","isPartOf":{"@id":"https:\/\/fundaciocatalunyacultura.cat\/#website"},"datePublished":"2021-03-30T08:42:36+00:00","dateModified":"2026-07-07T09:10:27+00:00","breadcrumb":{"@id":"https:\/\/fundaciocatalunyacultura.cat\/es\/premi-empresa-cultura\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fundaciocatalunyacultura.cat\/es\/premi-empresa-cultura\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fundaciocatalunyacultura.cat\/es\/premi-empresa-cultura\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.fundaciocatalunyacultura.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Premio EMPRESA CULTURA"}]},{"@type":"WebSite","@id":"https:\/\/fundaciocatalunyacultura.cat\/#website","url":"https:\/\/fundaciocatalunyacultura.cat\/","name":"Fundaci\u00f3 Catalunya Cultura","description":"","publisher":{"@id":"https:\/\/fundaciocatalunyacultura.cat\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fundaciocatalunyacultura.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fundaciocatalunyacultura.cat\/#organization","name":"Fundaci\u00f3 Catalunya Cultura","url":"https:\/\/fundaciocatalunyacultura.cat\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fundaciocatalunyacultura.cat\/#\/schema\/logo\/image\/","url":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/fundacio-catalunya-cultura\/uploads\/2021\/03\/fcc_logo_blanc-scaled.jpeg","contentUrl":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/fundacio-catalunya-cultura\/uploads\/2021\/03\/fcc_logo_blanc-scaled.jpeg","width":2560,"height":1785,"caption":"Fundaci\u00f3 Catalunya Cultura"},"image":{"@id":"https:\/\/fundaciocatalunyacultura.cat\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fundaciocatalunyacultura\/","https:\/\/x.com\/fcatcultura","https:\/\/www.linkedin.com\/company\/fundaci\u00f3-catalunya-cultura\/","https:\/\/ca.wikipedia.org\/wiki\/Fundaci\u00f3_Catalunya_Cultura"]}]}},"_links":{"self":[{"href":"https:\/\/fundaciocatalunyacultura.cat\/es\/wp-json\/wp\/v2\/pages\/4210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fundaciocatalunyacultura.cat\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fundaciocatalunyacultura.cat\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fundaciocatalunyacultura.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fundaciocatalunyacultura.cat\/es\/wp-json\/wp\/v2\/comments?post=4210"}],"version-history":[{"count":102,"href":"https:\/\/fundaciocatalunyacultura.cat\/es\/wp-json\/wp\/v2\/pages\/4210\/revisions"}],"predecessor-version":[{"id":30626,"href":"https:\/\/fundaciocatalunyacultura.cat\/es\/wp-json\/wp\/v2\/pages\/4210\/revisions\/30626"}],"wp:attachment":[{"href":"https:\/\/fundaciocatalunyacultura.cat\/es\/wp-json\/wp\/v2\/media?parent=4210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}